{"id":3781,"date":"2025-05-25T18:05:43","date_gmt":"2025-05-25T18:05:43","guid":{"rendered":"https:\/\/www.ticdoc.net\/?p=3781"},"modified":"2025-09-14T15:03:24","modified_gmt":"2025-09-14T15:03:24","slug":"google-i-o-2025-nuevas-funcionalidades-de-gemini-integradas-en-canvas","status":"publish","type":"post","link":"https:\/\/www.ticdoc.net\/es\/2025\/05\/25\/google-i-o-2025-nuevas-funcionalidades-de-gemini-integradas-en-canvas\/","title":{"rendered":"Google I\/O 2025: nuevas funcionalidades de Gemini integradas en Canvas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El 21 de mayo de 2025, durante el evento Google I\/O 2025, Google present\u00f3 una evoluci\u00f3n significativa de su ecosistema de inteligencia artificial: <strong>Gemini<\/strong>. Esta nueva etapa se centra en convertir Gemini en una herramienta m\u00e1s personalizada, proactiva y plenamente multimodal, capaz de interpretar el contexto e interactuar mediante voz, texto, imagen y v\u00eddeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este anuncio marca tambi\u00e9n un cambio estrat\u00e9gico relevante. Hasta ahora, Google hab\u00eda mantenido una posici\u00f3n relativamente prudente en el \u00e1mbito de la IA generativa, priorizando la seguridad y la fiabilidad. Ahora, sin embargo, ha acelerado el ritmo de innovaci\u00f3n, aline\u00e1ndose con el paso de competidores como OpenAI, Anthropic, Meta y diversos actores emergentes en China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las nuevas funcionalidades de <strong>Gemini PRO<\/strong> estar\u00e1n disponibles en las licencias Google Workspace Standard, Business Plus y Enterprise, as\u00ed como a trav\u00e9s de Google One IA Pro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una de las novedades m\u00e1s destacadas: Canvas integrado con Gemini<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las funcionalidades m\u00e1s relevantes es la integraci\u00f3n y mejora de <strong>Canvas<\/strong>, un nuevo entorno de interacci\u00f3n visual con IA generativa dentro del ecosistema Gemini. A diferencia del modelo tradicional de chat, Canvas se concibe como un editor visual estructurado, que permite construir respuestas con estilo, jerarqu\u00eda y funcionalidades enriquecidas (tambi\u00e9n disponible en otras plataformas como ChatGPT).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre sus posibilidades, destacan:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Generaci\u00f3n de texto mejorada con Gemini Flash 2.5 Pro<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Este nuevo modelo optimiza la calidad y precisi\u00f3n textual, destacando por su rapidez en res\u00famenes, contenidos breves y asistencia proactiva.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Creaci\u00f3n autom\u00e1tica de p\u00e1ginas web<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Canvas permite generar p\u00e1ginas web a partir de una simple petici\u00f3n textual. Las p\u00e1ginas incluyen men\u00fas, gr\u00e1ficos, elementos interactivos y dise\u00f1o adaptable, y el sistema permite descargar el c\u00f3digo HTML, CSS y JavaScript para su publicaci\u00f3n o integraci\u00f3n en entornos como Google Sites, o cualquier otro tipo de web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ser\u00eda deseable que, en futuras actualizaciones, se a\u00f1adiera la posibilidad de compartirlas directamente mediante enlaces temporales o publicaci\u00f3n en la nube de Google.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"471\" src=\"https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-1024x471.png\" alt=\"\" class=\"wp-image-3441\" srcset=\"https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-1024x471.png 1024w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-300x138.png 300w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-768x354.png 768w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-1536x707.png 1536w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-485x223.png 485w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-400x184.png 400w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-1260x580.png 1260w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-869x400.png 869w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-700x322.png 700w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-900x414.png 900w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-600x276.png 600w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-1400x645.png 1400w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-225x104.png 225w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-325x150.png 325w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-1320x608.png 1320w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-660x304.png 660w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-440x203.png 440w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-330x152.png 330w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-670x308.png 670w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-210x97.png 210w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-420x193.png 420w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-200x92.png 200w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-310x143.png 310w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-230x106.png 230w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-30x14.png 30w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1-60x28.png 60w, https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini3-1.png 1831w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Generaci\u00f3n de infograf\u00edas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra funcionalidad relevante es la generaci\u00f3n autom\u00e1tica de infograf\u00edas a partir de textos o datos. Estas son \u00fatiles para la visualizaci\u00f3n r\u00e1pida de la informaci\u00f3n y se pueden descargar como c\u00f3digo, aunque todav\u00eda no se pueden compartir directamente desde Gemini.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/gemini4-1024x470.png\" alt=\"\" class=\"wp-image-3443\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Res\u00famenes en formato p\u00f3dcast<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Google incorpora la capacidad de generar audios autom\u00e1ticos a partir de textos, ahora plenamente integrados a trav\u00e9s de Canvas. Esta funcionalidad, hasta ahora solo disponible en NotebookLM, permite obtener res\u00famenes orales para difusi\u00f3n, accesibilidad o formaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el momento, estos audios no est\u00e1n en lengua catalana, pero ya est\u00e1n disponibles en castellano. Como muestra, os adjunto uno con informaci\u00f3n sobre las \u00faltimas novedades de Google I\/O 2025.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.ticdoc.net\/wp-content\/uploads\/2025\/05\/Gemini-AI-Unveiled_-Your-Personal-AI-Revolution-is-Here-and-its-Everywhere-1.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El 21 de mayo de 2025, durante el evento Google I\/O 2025, Google present\u00f3 una evoluci\u00f3n significativa de su ecosistema de inteligencia artificial: Gemini. Esta nueva etapa se centra en convertir Gemini en una herramienta m\u00e1s personalizada, proactiva y plenamente multimodal, capaz de interpretar el contexto e interactuar mediante voz, texto, imagen y v\u00eddeo. Este [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3618,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67],"tags":[428,448,447],"class_list":["post-3781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inteligencia-artificial-es","tag-gemini-3","tag-google-3","tag-inteligencia-artificial-3"],"views":372,"_links":{"self":[{"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/posts\/3781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/comments?post=3781"}],"version-history":[{"count":1,"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/posts\/3781\/revisions"}],"predecessor-version":[{"id":3784,"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/posts\/3781\/revisions\/3784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/media\/3618"}],"wp:attachment":[{"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/media?parent=3781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/categories?post=3781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ticdoc.net\/es\/wp-json\/wp\/v2\/tags?post=3781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}